<style type="text/css">
	.andrasortering-hide {
		display:none!important;
	}
</style>
{"id":19867,"date":"2015-08-13T16:14:48","date_gmt":"2015-08-13T14:14:48","guid":{"rendered":"http:\/\/test.woolpower.se.hemsida.eu\/shop\/produkt\/long-johns-400\/"},"modified":"2022-12-27T19:54:13","modified_gmt":"2022-12-27T18:54:13","slug":"long-johns-400","status":"publish","type":"product","link":"https:\/\/test.woolpower.se\/en\/shop\/produkt\/long-johns-400\/","title":{"rendered":"Long Johns 400"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Long Johns 400 are made of circular knit fabric and have no lengthwise seams. A gusset in the back ensures optimal comfort. Cuffs are knitted in.<\/p>\n<p>From size XL and upwards, there is also a sewn-in gusset at the front. [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"https:\/\/test.woolpower.se\/en\/shop\/produkt\/long-johns-400\/\">Read More&#8230;<\/a><\/p>\n","protected":false},"featured_media":37730,"template":"","meta":[],"product_cat":[128],"product_tag":[151],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Long Johns 400 - Woolpower Test<\/title>\n<meta name=\"description\" content=\"B\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Long Johns 400 - Woolpower Test\" \/>\n<meta property=\"og:description\" content=\"B\" \/>\n<meta property=\"og:url\" content=\"https:\/\/test.woolpower.se\/en\/shop\/produkt\/long-johns-400\/\" \/>\n<meta property=\"og:site_name\" content=\"Woolpower Test\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-27T18:54:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/test.woolpower.se\/wp-content\/uploads\/long-johns-400-black-male-isolated.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/test.woolpower.se\/en\/shop\/produkt\/long-johns-400\/\",\"url\":\"https:\/\/test.woolpower.se\/en\/shop\/produkt\/long-johns-400\/\",\"name\":\"Long Johns 400 - Woolpower Test\",\"isPartOf\":{\"@id\":\"https:\/\/test.woolpower.se\/en\/#website\"},\"datePublished\":\"2015-08-13T14:14:48+00:00\",\"dateModified\":\"2022-12-27T18:54:13+00:00\",\"description\":\"B\",\"breadcrumb\":{\"@id\":\"https:\/\/test.woolpower.se\/en\/shop\/produkt\/long-johns-400\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/test.woolpower.se\/en\/shop\/produkt\/long-johns-400\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/test.woolpower.se\/en\/shop\/produkt\/long-johns-400\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hem\",\"item\":\"https:\/\/test.woolpower.se\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Our Products\",\"item\":\"https:\/\/test.woolpower.se\/en\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Long Johns 400\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/test.woolpower.se\/en\/#website\",\"url\":\"https:\/\/test.woolpower.se\/en\/\",\"name\":\"Woolpower Test\",\"description\":\"Responsibly made in Sweden\",\"publisher\":{\"@id\":\"https:\/\/test.woolpower.se\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/test.woolpower.se\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/test.woolpower.se\/en\/#organization\",\"name\":\"Woolpower\",\"url\":\"https:\/\/test.woolpower.se\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/test.woolpower.se\/en\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/test.woolpower.se\/wp-content\/uploads\/Woolpower_logo-2705x546--e1636015780215.png\",\"contentUrl\":\"http:\/\/test.woolpower.se\/wp-content\/uploads\/Woolpower_logo-2705x546--e1636015780215.png\",\"width\":300,\"height\":61,\"caption\":\"Woolpower\"},\"image\":{\"@id\":\"https:\/\/test.woolpower.se\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Long Johns 400 - Woolpower Test","description":"B","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Long Johns 400 - Woolpower Test","og_description":"B","og_url":"https:\/\/test.woolpower.se\/en\/shop\/produkt\/long-johns-400\/","og_site_name":"Woolpower Test","article_modified_time":"2022-12-27T18:54:13+00:00","og_image":[{"width":1600,"height":1600,"url":"https:\/\/test.woolpower.se\/wp-content\/uploads\/long-johns-400-black-male-isolated.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/test.woolpower.se\/en\/shop\/produkt\/long-johns-400\/","url":"https:\/\/test.woolpower.se\/en\/shop\/produkt\/long-johns-400\/","name":"Long Johns 400 - Woolpower Test","isPartOf":{"@id":"https:\/\/test.woolpower.se\/en\/#website"},"datePublished":"2015-08-13T14:14:48+00:00","dateModified":"2022-12-27T18:54:13+00:00","description":"B","breadcrumb":{"@id":"https:\/\/test.woolpower.se\/en\/shop\/produkt\/long-johns-400\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/test.woolpower.se\/en\/shop\/produkt\/long-johns-400\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/test.woolpower.se\/en\/shop\/produkt\/long-johns-400\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hem","item":"https:\/\/test.woolpower.se\/en\/"},{"@type":"ListItem","position":2,"name":"Our Products","item":"https:\/\/test.woolpower.se\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Long Johns 400"}]},{"@type":"WebSite","@id":"https:\/\/test.woolpower.se\/en\/#website","url":"https:\/\/test.woolpower.se\/en\/","name":"Woolpower Test","description":"Responsibly made in Sweden","publisher":{"@id":"https:\/\/test.woolpower.se\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/test.woolpower.se\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/test.woolpower.se\/en\/#organization","name":"Woolpower","url":"https:\/\/test.woolpower.se\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/test.woolpower.se\/en\/#\/schema\/logo\/image\/","url":"http:\/\/test.woolpower.se\/wp-content\/uploads\/Woolpower_logo-2705x546--e1636015780215.png","contentUrl":"http:\/\/test.woolpower.se\/wp-content\/uploads\/Woolpower_logo-2705x546--e1636015780215.png","width":300,"height":61,"caption":"Woolpower"},"image":{"@id":"https:\/\/test.woolpower.se\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/test.woolpower.se\/en\/wp-json\/wp\/v2\/product\/19867"}],"collection":[{"href":"https:\/\/test.woolpower.se\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/test.woolpower.se\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/test.woolpower.se\/en\/wp-json\/wp\/v2\/media\/37730"}],"wp:attachment":[{"href":"https:\/\/test.woolpower.se\/en\/wp-json\/wp\/v2\/media?parent=19867"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/test.woolpower.se\/en\/wp-json\/wp\/v2\/product_cat?post=19867"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/test.woolpower.se\/en\/wp-json\/wp\/v2\/product_tag?post=19867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}